{"id":1675,"date":"2025-08-04T12:44:40","date_gmt":"2025-08-04T12:44:40","guid":{"rendered":"https:\/\/www.paulaluise.it\/?page_id=1675"},"modified":"2026-06-03T07:21:05","modified_gmt":"2026-06-03T07:21:05","slug":"ueber-mich","status":"publish","type":"page","link":"https:\/\/www.paulaluise.it\/de\/ueber-mich\/","title":{"rendered":"\u00dcber mich"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1675\" class=\"elementor elementor-1675\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21576190 e-grid e-con-full animated-fast elementor-invisible e-con e-parent\" data-id=\"21576190\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;400&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f771d9c elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"1f771d9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1145\" height=\"1527\" src=\"https:\/\/www.paulaluise.it\/wp-content\/uploads\/2023\/04\/vfoge8325-2.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-304\" alt=\"\" srcset=\"https:\/\/www.paulaluise.it\/wp-content\/uploads\/2023\/04\/vfoge8325-2.jpg 1145w, https:\/\/www.paulaluise.it\/wp-content\/uploads\/2023\/04\/vfoge8325-2-225x300.jpg 225w, https:\/\/www.paulaluise.it\/wp-content\/uploads\/2023\/04\/vfoge8325-2-768x1024.jpg 768w\" sizes=\"(max-width: 1145px) 100vw, 1145px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3961a37 e-con-full e-flex e-con e-child\" data-id=\"3961a37\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bf4c0cc elementor-widget elementor-widget-heading\" data-id=\"5bf4c0cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00dcber mich<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60f7bc41 elementor-widget elementor-widget-text-editor\" data-id=\"60f7bc41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">In meiner Arbeit schaffe ich Raum zum Sein \u2014 keine Performance, keine Agenda \u2014 mit somatischen und intuitiven Praktiken, um dein Nervensystem und dein allgemeines psychophysisches Wohlbefinden zu unterst\u00fctzen. Ich bin fasziniert vom Nervensystem und davon, wie unser Gehirn mit und durch den K\u00f6rper kommuniziert. Deshalb integriere ich in alles, was ich anbiete, Strategien zur F\u00f6rderung von Frieden und Sicherheit im System \u2014 durch somatische und traumasensible Ans\u00e4tze.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Ich studiere, praktiziere und unterrichte Vinyasa, Yin und Yoga Nidra und bereichere meine Praxis mit somatischen Elementen. Als Doula begleite ich Einzelpersonen und Paare durch die Zeit vor, w\u00e4hrend und nach der Schwangerschaft und unterst\u00fctze sie mit praktischen Werkzeugen f\u00fcr einen achtsamen und bewussten Weg in die Elternschaft. Ich lebe, praktiziere und unterrichte in Bologna und online.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Mein Ansatz hilft dabei, eine authentische Verbindung mit dem K\u00f6rper, den Emotionen und der inneren Energie wiederherzustellen \u2014 und f\u00f6rdert so innere Ruhe und Frieden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42aa580 e-flex e-con-boxed e-con e-parent\" data-id=\"42aa580\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ca7a15e e-con-full e-flex e-con e-child\" data-id=\"ca7a15e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16754f52 e-grid e-con-full animated-fast e-con e-parent\" data-id=\"16754f52\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:&quot;400&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fda35f1 e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"fda35f1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd62ab2 elementor-widget elementor-widget-heading\" data-id=\"fd62ab2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Meine LehrerInnen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3534ef07 elementor-widget elementor-widget-text-editor\" data-id=\"3534ef07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Ich bin eine von der Yoga Alliance zertifizierte Yogalehrerin mit \u00fcber 500 Ausbildungsstunden in verschiedenen Bereichen: Prema Vinyasa Yoga, Yin Yoga, Trauma-informiertes Yoga, Restoratives Yoga, Yoga Nidra, Yoga f\u00fcr diverse K\u00f6rper sowie Yoga in der Schwangerschaft und im Wochenbett. Au\u00dferdem bin ich eine zertifizierte Full-Spectrum-Doula bei WombExpansion und habe Zertifikate in Ayurvedischer Ern\u00e4hrung sowie als Somatic Movement and Breathwork for Trauma Healing Practitioner erworben.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Ich bin zutiefst dankbar f\u00fcr all jene, die meinen Weg mitgepr\u00e4gt haben \u2014 manche durch direkte Begegnung, manche durch ihre Werke und Forschung, manche durch das allt\u00e4gliche Teilen der Praxis.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Ich hatte das Gl\u00fcck, im Yoga bei Ameriga Giannone, Tina Hilbert, Michel Young, Dr. Arielle Schwartz und Dr. Scott Lyons zu lernen, und bei vielen anderen \u2014 jede von ihnen hat eine tiefe Spur in meiner Art zu arbeiten hinterlassen.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Auf meinem Weg als Doula hatte ich das Privileg, von Denise Petrikat, Nadja Brenneisen, Hannah Ladda und Sabrina Leo zu lernen, und von vielen anderen wertvollen Menschen, die mich auf diesem Weg begleitet haben.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Nicht alle bedeutsamen Begegnungen finden pers\u00f6nlich statt, und doch haben einige f\u00fcr immer ver\u00e4ndert, wie ich praktiziere und unterrichte. Durch mein Studium konnte ich von Bernie Clark, Paul Grilley, Sarah Powers, Eckhart Tolle, Rumi, Swami Satyananda Saraswati, Bessel van der Kolk, Gabor Mat\u00e9 und Peter Levine lernen, und von vielen anderen Stimmen, die meine Praxis bis heute bewohnen.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Dann gibt es jene, deren Praxis mich t\u00e4glich inspiriert: Adriene Mishler, Lisa Weinhold, Cole Chance, und viele andere \u2014 darunter meine Freundinnen Chiara, Sara und Bianca, mit denen ich mich st\u00e4ndig austausche, auf eine Art, die ich immer wieder bereichernd und sch\u00f6n finde.<\/p><p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Ich spreche tiefen Dank aus an alle Lehrerinnen, die mich bis hierher begleitet haben. Am Ende seid ihr meine gr\u00f6\u00dften Lehrerinnen: ihr, die ihr zur Praxis kommt, mir Feedback gebt, mir zeigt, wie sich eure K\u00f6rper bewegen m\u00f6chten, was resoniert und was ihr braucht. Danke, dass ihr seid \u2661<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29a1fd38 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"29a1fd38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.paulaluise.it\/services\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Meine Angebote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eeeb9d0 animated-fast elementor-invisible elementor-widget elementor-widget-image\" data-id=\"eeeb9d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.paulaluise.it\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-05-17-at-22.32.00-1-768x1024.jpeg\" class=\"attachment-large size-large wp-image-2502\" alt=\"\" srcset=\"https:\/\/www.paulaluise.it\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-05-17-at-22.32.00-1-768x1024.jpeg 768w, https:\/\/www.paulaluise.it\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-05-17-at-22.32.00-1-225x300.jpeg 225w, https:\/\/www.paulaluise.it\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-05-17-at-22.32.00-1-1152x1536.jpeg 1152w, https:\/\/www.paulaluise.it\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-05-17-at-22.32.00-1.jpeg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9d8f16 e-flex e-con-boxed e-con e-parent\" data-id=\"a9d8f16\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f6a87c7 e-con-full e-flex e-con e-child\" data-id=\"f6a87c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a918d92 elementor-widget elementor-widget-video\" data-id=\"a918d92\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/XFNDWb_pW4o&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-536e781 e-con-full e-flex e-con e-child\" data-id=\"536e781\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbb81be elementor-widget elementor-widget-heading\" data-id=\"dbb81be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/youtu.be\/_C4AyoqK2gw\">Ein paar Worte zu meinem Weg und meinem Unterrichtsstil<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00dcber mich In meiner Arbeit schaffe ich Raum zum Sein \u2014 keine Performance, keine Agenda \u2014 mit somatischen und intuitiven Praktiken, um dein Nervensystem und dein allgemeines psychophysisches Wohlbefinden zu unterst\u00fctzen. Ich bin fasziniert vom Nervensystem und davon, wie unser Gehirn mit und durch den K\u00f6rper kommuniziert. Deshalb integriere ich in alles, was ich anbiete, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1675","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.paulaluise.it\/de\/wp-json\/wp\/v2\/pages\/1675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.paulaluise.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.paulaluise.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.paulaluise.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paulaluise.it\/de\/wp-json\/wp\/v2\/comments?post=1675"}],"version-history":[{"count":13,"href":"https:\/\/www.paulaluise.it\/de\/wp-json\/wp\/v2\/pages\/1675\/revisions"}],"predecessor-version":[{"id":2523,"href":"https:\/\/www.paulaluise.it\/de\/wp-json\/wp\/v2\/pages\/1675\/revisions\/2523"}],"wp:attachment":[{"href":"https:\/\/www.paulaluise.it\/de\/wp-json\/wp\/v2\/media?parent=1675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}